{"id":98838,"date":"2023-09-19T11:29:52","date_gmt":"2023-09-19T09:29:52","guid":{"rendered":"https:\/\/faguowenhua.com\/?post_type=cine_events&#038;p=98838"},"modified":"2023-09-19T11:29:52","modified_gmt":"2023-09-19T09:29:52","slug":"la-panthere-des-neiges","status":"publish","type":"cine_events","link":"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/","title":{"rendered":"(Fr) LA PANTH\u00c8RE DES NEIGES"},"parent":0,"menu_order":524,"template":"","tags":[566],"evenement-ifp":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>(Fr) LA PANTH\u00c8RE DES NEIGES - Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Fr) LA PANTH\u00c8RE DES NEIGES - Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine\" \/>\n<meta property=\"og:image\" content=\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@InstitutFrChine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/\",\"url\":\"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/\",\"name\":\"(Fr) LA PANTH\u00c8RE DES NEIGES - Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine\",\"isPartOf\":{\"@id\":\"https:\/\/faguowenhua.com\/en\/#website\"},\"datePublished\":\"2023-09-19T09:29:52+00:00\",\"dateModified\":\"2023-09-19T09:29:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/faguowenhua.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA PANTH\u00c8RE DES NEIGES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faguowenhua.com\/en\/#website\",\"url\":\"https:\/\/faguowenhua.com\/en\/\",\"name\":\"Institut fran\u00e7ais de Chine\",\"description\":\"La Culture fran\u00e7aise en Chine\",\"publisher\":{\"@id\":\"https:\/\/faguowenhua.com\/en\/#organization\"},\"alternateName\":\"La Culture fran\u00e7aise en Chine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faguowenhua.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faguowenhua.com\/en\/#organization\",\"name\":\"Institut fran\u00e7ais de Chine\",\"alternateName\":\"Culture fran\u00e7aise en Chine\",\"url\":\"https:\/\/faguowenhua.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/faguowenhua.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"contentUrl\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"width\":696,\"height\":696,\"caption\":\"Institut fran\u00e7ais de Chine\"},\"image\":{\"@id\":\"https:\/\/faguowenhua.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/InstitutFrChine\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Fr) LA PANTH\u00c8RE DES NEIGES - Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"(Fr) LA PANTH\u00c8RE DES NEIGES - Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine","og_url":"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/","og_site_name":"Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine","og_image":[{"width":1200,"height":675,"url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@InstitutFrChine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/","url":"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/","name":"(Fr) LA PANTH\u00c8RE DES NEIGES - Institut fran\u00e7ais Chine - La Culture fran\u00e7aise en Chine","isPartOf":{"@id":"https:\/\/faguowenhua.com\/en\/#website"},"datePublished":"2023-09-19T09:29:52+00:00","dateModified":"2023-09-19T09:29:52+00:00","breadcrumb":{"@id":"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/faguowenhua.com\/en\/evenement-cinema\/la-panthere-des-neiges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/faguowenhua.com\/en\/"},{"@type":"ListItem","position":2,"name":"LA PANTH\u00c8RE DES NEIGES"}]},{"@type":"WebSite","@id":"https:\/\/faguowenhua.com\/en\/#website","url":"https:\/\/faguowenhua.com\/en\/","name":"Institut fran\u00e7ais de Chine","description":"La Culture fran\u00e7aise en Chine","publisher":{"@id":"https:\/\/faguowenhua.com\/en\/#organization"},"alternateName":"La Culture fran\u00e7aise en Chine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faguowenhua.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/faguowenhua.com\/en\/#organization","name":"Institut fran\u00e7ais de Chine","alternateName":"Culture fran\u00e7aise en Chine","url":"https:\/\/faguowenhua.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/faguowenhua.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","contentUrl":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","width":696,"height":696,"caption":"Institut fran\u00e7ais de Chine"},"image":{"@id":"https:\/\/faguowenhua.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/InstitutFrChine"]}]}},"_links":{"self":[{"href":"https:\/\/faguowenhua.com\/en\/wp-json\/wp\/v2\/cine_events\/98838"}],"collection":[{"href":"https:\/\/faguowenhua.com\/en\/wp-json\/wp\/v2\/cine_events"}],"about":[{"href":"https:\/\/faguowenhua.com\/en\/wp-json\/wp\/v2\/types\/cine_events"}],"wp:attachment":[{"href":"https:\/\/faguowenhua.com\/en\/wp-json\/wp\/v2\/media?parent=98838"}],"wp:term":[{"taxonomy":"tags","embeddable":true,"href":"https:\/\/faguowenhua.com\/en\/wp-json\/wp\/v2\/tags?post=98838"},{"taxonomy":"evenement-ifp","embeddable":true,"href":"https:\/\/faguowenhua.com\/en\/wp-json\/wp\/v2\/evenement-ifp?post=98838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}