{"id":99158,"date":"2023-10-05T11:31:36","date_gmt":"2023-10-05T09:31:36","guid":{"rendered":"https:\/\/faguowenhua.com\/?post_type=cine_events&#038;p=99158"},"modified":"2023-11-01T16:17:28","modified_gmt":"2023-11-01T15:17:28","slug":"la-glace-et-le-ciel","status":"publish","type":"cine_events","link":"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/","title":{"rendered":"\u51b0\u5ddd\u4e0e\u82cd\u7a79"},"parent":0,"menu_order":511,"template":"","tags":[452,449,566],"evenement-ifp":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u51b0\u5ddd\u4e0e\u82cd\u7a79 - \u6cd5\u56fd\u6587\u5316<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u51b0\u5ddd\u4e0e\u82cd\u7a79 - \u6cd5\u56fd\u6587\u5316\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6cd5\u56fd\u6587\u5316\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-01T15:17:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@InstitutFrChine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/\",\"url\":\"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/\",\"name\":\"\u51b0\u5ddd\u4e0e\u82cd\u7a79 - \u6cd5\u56fd\u6587\u5316\",\"isPartOf\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#website\"},\"datePublished\":\"2023-10-05T09:31:36+00:00\",\"dateModified\":\"2023-11-01T15:17:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/faguowenhua.com\/zh\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Glace et le Ciel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#website\",\"url\":\"https:\/\/faguowenhua.com\/zh\/\",\"name\":\"Institut fran\u00e7ais de Chine\",\"description\":\"\u6cd5\u56fd\u6587\u5316\u4e2d\u5fc3\",\"publisher\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#organization\"},\"alternateName\":\"La Culture fran\u00e7aise en Chine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faguowenhua.com\/zh\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#organization\",\"name\":\"Institut fran\u00e7ais de Chine\",\"alternateName\":\"Culture fran\u00e7aise en Chine\",\"url\":\"https:\/\/faguowenhua.com\/zh\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-CN\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"contentUrl\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"width\":696,\"height\":696,\"caption\":\"Institut fran\u00e7ais de Chine\"},\"image\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/InstitutFrChine\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u51b0\u5ddd\u4e0e\u82cd\u7a79 - \u6cd5\u56fd\u6587\u5316","robots":{"index":"noindex","follow":"follow"},"og_locale":"zh_CN","og_type":"article","og_title":"\u51b0\u5ddd\u4e0e\u82cd\u7a79 - \u6cd5\u56fd\u6587\u5316","og_url":"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/","og_site_name":"\u6cd5\u56fd\u6587\u5316","article_modified_time":"2023-11-01T15:17:28+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@InstitutFrChine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/","url":"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/","name":"\u51b0\u5ddd\u4e0e\u82cd\u7a79 - \u6cd5\u56fd\u6587\u5316","isPartOf":{"@id":"https:\/\/faguowenhua.com\/zh\/#website"},"datePublished":"2023-10-05T09:31:36+00:00","dateModified":"2023-11-01T15:17:28+00:00","breadcrumb":{"@id":"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/faguowenhua.com\/zh\/evenement-cinema\/la-glace-et-le-ciel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/faguowenhua.com\/zh\/"},{"@type":"ListItem","position":2,"name":"La Glace et le Ciel"}]},{"@type":"WebSite","@id":"https:\/\/faguowenhua.com\/zh\/#website","url":"https:\/\/faguowenhua.com\/zh\/","name":"Institut fran\u00e7ais de Chine","description":"\u6cd5\u56fd\u6587\u5316\u4e2d\u5fc3","publisher":{"@id":"https:\/\/faguowenhua.com\/zh\/#organization"},"alternateName":"La Culture fran\u00e7aise en Chine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faguowenhua.com\/zh\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"Organization","@id":"https:\/\/faguowenhua.com\/zh\/#organization","name":"Institut fran\u00e7ais de Chine","alternateName":"Culture fran\u00e7aise en Chine","url":"https:\/\/faguowenhua.com\/zh\/","logo":{"@type":"ImageObject","inLanguage":"zh-CN","@id":"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","contentUrl":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","width":696,"height":696,"caption":"Institut fran\u00e7ais de Chine"},"image":{"@id":"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/InstitutFrChine"]}]}},"_links":{"self":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/cine_events\/99158"}],"collection":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/cine_events"}],"about":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/types\/cine_events"}],"wp:attachment":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/media?parent=99158"}],"wp:term":[{"taxonomy":"tags","embeddable":true,"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/tags?post=99158"},{"taxonomy":"evenement-ifp","embeddable":true,"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/evenement-ifp?post=99158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}