{"id":103793,"date":"2025-04-08T04:19:49","date_gmt":"2025-04-08T02:19:49","guid":{"rendered":"https:\/\/faguowenhua.com\/?post_type=event&#038;p=103793"},"modified":"2025-04-08T04:19:49","modified_gmt":"2025-04-08T02:19:49","slug":"laurent-petitgirard","status":"publish","type":"event","link":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/","title":{"rendered":"\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14"},"featured_media":0,"parent":0,"menu_order":266,"template":"","tags":[587,381],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14 - \u6cd5\u56fd\u6587\u5316<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14 - \u6cd5\u56fd\u6587\u5316\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6cd5\u56fd\u6587\u5316\" \/>\n<meta property=\"og:image\" content=\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@InstitutFrChine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/\",\"url\":\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/\",\"name\":\"\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14 - \u6cd5\u56fd\u6587\u5316\",\"isPartOf\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#website\"},\"datePublished\":\"2025-04-08T02:19:49+00:00\",\"dateModified\":\"2025-04-08T02:19:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/faguowenhua.com\/zh\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laurent Petitgirard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#website\",\"url\":\"https:\/\/faguowenhua.com\/zh\/\",\"name\":\"Institut fran\u00e7ais de Chine\",\"description\":\"\u6cd5\u56fd\u6587\u5316\u4e2d\u5fc3\",\"publisher\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#organization\"},\"alternateName\":\"La Culture fran\u00e7aise en Chine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faguowenhua.com\/zh\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#organization\",\"name\":\"Institut fran\u00e7ais de Chine\",\"alternateName\":\"Culture fran\u00e7aise en Chine\",\"url\":\"https:\/\/faguowenhua.com\/zh\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-CN\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"contentUrl\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"width\":696,\"height\":696,\"caption\":\"Institut fran\u00e7ais de Chine\"},\"image\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/InstitutFrChine\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14 - \u6cd5\u56fd\u6587\u5316","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/","og_locale":"zh_CN","og_type":"article","og_title":"\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14 - \u6cd5\u56fd\u6587\u5316","og_url":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/","og_site_name":"\u6cd5\u56fd\u6587\u5316","og_image":[{"width":1200,"height":675,"url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@InstitutFrChine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/","url":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/","name":"\u6d1b\u6717\u00b7\u4f69\u8482\u5409\u62c9\u5c14 - \u6cd5\u56fd\u6587\u5316","isPartOf":{"@id":"https:\/\/faguowenhua.com\/zh\/#website"},"datePublished":"2025-04-08T02:19:49+00:00","dateModified":"2025-04-08T02:19:49+00:00","breadcrumb":{"@id":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/faguowenhua.com\/zh\/event\/laurent-petitgirard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/faguowenhua.com\/zh\/"},{"@type":"ListItem","position":2,"name":"Laurent Petitgirard"}]},{"@type":"WebSite","@id":"https:\/\/faguowenhua.com\/zh\/#website","url":"https:\/\/faguowenhua.com\/zh\/","name":"Institut fran\u00e7ais de Chine","description":"\u6cd5\u56fd\u6587\u5316\u4e2d\u5fc3","publisher":{"@id":"https:\/\/faguowenhua.com\/zh\/#organization"},"alternateName":"La Culture fran\u00e7aise en Chine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faguowenhua.com\/zh\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"Organization","@id":"https:\/\/faguowenhua.com\/zh\/#organization","name":"Institut fran\u00e7ais de Chine","alternateName":"Culture fran\u00e7aise en Chine","url":"https:\/\/faguowenhua.com\/zh\/","logo":{"@type":"ImageObject","inLanguage":"zh-CN","@id":"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","contentUrl":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","width":696,"height":696,"caption":"Institut fran\u00e7ais de Chine"},"image":{"@id":"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/InstitutFrChine"]}]}},"_links":{"self":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/event\/103793"}],"collection":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/media?parent=103793"}],"wp:term":[{"taxonomy":"tags","embeddable":true,"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/tags?post=103793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}