{"id":91330,"date":"2019-06-24T01:00:00","date_gmt":"2019-06-23T23:00:00","guid":{"rendered":""},"modified":"2023-04-21T06:58:22","modified_gmt":"2023-04-21T04:58:22","slug":"lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019","status":"publish","type":"event","link":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/","title":{"rendered":"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019"},"featured_media":0,"parent":0,"menu_order":1578,"template":"","tags":[483,381],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019 - \u6cd5\u56fd\u6587\u5316<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019 - \u6cd5\u56fd\u6587\u5316\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6cd5\u56fd\u6587\u5316\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-21T04:58:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@InstitutFrChine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/\",\"url\":\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/\",\"name\":\"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019 - \u6cd5\u56fd\u6587\u5316\",\"isPartOf\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#website\"},\"datePublished\":\"2019-06-23T23:00:00+00:00\",\"dateModified\":\"2023-04-21T04:58:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/#breadcrumb\"},\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/faguowenhua.com\/zh\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#website\",\"url\":\"https:\/\/faguowenhua.com\/zh\/\",\"name\":\"Institut fran\u00e7ais de Chine\",\"description\":\"\u6cd5\u56fd\u6587\u5316\u4e2d\u5fc3\",\"publisher\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#organization\"},\"alternateName\":\"La Culture fran\u00e7aise en Chine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faguowenhua.com\/zh\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#organization\",\"name\":\"Institut fran\u00e7ais de Chine\",\"alternateName\":\"Culture fran\u00e7aise en Chine\",\"url\":\"https:\/\/faguowenhua.com\/zh\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-CN\",\"@id\":\"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"contentUrl\":\"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg\",\"width\":696,\"height\":696,\"caption\":\"Institut fran\u00e7ais de Chine\"},\"image\":{\"@id\":\"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/twitter.com\/InstitutFrChine\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019 - \u6cd5\u56fd\u6587\u5316","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/","og_locale":"zh_CN","og_type":"article","og_title":"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019 - \u6cd5\u56fd\u6587\u5316","og_url":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/","og_site_name":"\u6cd5\u56fd\u6587\u5316","article_modified_time":"2023-04-21T04:58:22+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/site-seo-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@InstitutFrChine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/","url":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/","name":"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019 - \u6cd5\u56fd\u6587\u5316","isPartOf":{"@id":"https:\/\/faguowenhua.com\/zh\/#website"},"datePublished":"2019-06-23T23:00:00+00:00","dateModified":"2023-04-21T04:58:22+00:00","breadcrumb":{"@id":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/#breadcrumb"},"inLanguage":"zh-CN","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/faguowenhua.com\/zh\/event\/lewis-ofman-revelation-de-la-scene-electro-francaise-fete-de-la-musique-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/faguowenhua.com\/zh\/"},{"@type":"ListItem","position":2,"name":"Lewis OfMan, r\u00e9v\u00e9lation de la sc\u00e8ne \u00e9lectro fran\u00e7aise | F\u00eate de la musique 2019"}]},{"@type":"WebSite","@id":"https:\/\/faguowenhua.com\/zh\/#website","url":"https:\/\/faguowenhua.com\/zh\/","name":"Institut fran\u00e7ais de Chine","description":"\u6cd5\u56fd\u6587\u5316\u4e2d\u5fc3","publisher":{"@id":"https:\/\/faguowenhua.com\/zh\/#organization"},"alternateName":"La Culture fran\u00e7aise en Chine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faguowenhua.com\/zh\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-CN"},{"@type":"Organization","@id":"https:\/\/faguowenhua.com\/zh\/#organization","name":"Institut fran\u00e7ais de Chine","alternateName":"Culture fran\u00e7aise en Chine","url":"https:\/\/faguowenhua.com\/zh\/","logo":{"@type":"ImageObject","inLanguage":"zh-CN","@id":"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/","url":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","contentUrl":"https:\/\/faguowenhua.com\/wp-content\/uploads\/2023\/06\/institutfrancais-chine-logo.jpg","width":696,"height":696,"caption":"Institut fran\u00e7ais de Chine"},"image":{"@id":"https:\/\/faguowenhua.com\/zh\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/twitter.com\/InstitutFrChine"]}]}},"_links":{"self":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/event\/91330"}],"collection":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/media?parent=91330"}],"wp:term":[{"taxonomy":"tags","embeddable":true,"href":"https:\/\/faguowenhua.com\/zh\/wp-json\/wp\/v2\/tags?post=91330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}